{"id":3945,"date":"2020-09-03T16:35:05","date_gmt":"2020-09-03T14:35:05","guid":{"rendered":"https:\/\/seedsoftellers.eu\/?post_type=resources&#038;p=3945"},"modified":"2020-10-21T16:34:12","modified_gmt":"2020-10-21T14:34:12","slug":"as-bodas-da-capoeira","status":"publish","type":"resources","link":"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/","title":{"rendered":"As bodas da capoeira"},"content":{"rendered":"\n<p>Diz um dia o galo \u00e0 galinha:<br>\u2013 Casaremos a nossa filhinha!<br>\u2013 Casaremos ou n\u00e3o casaremos,<br>Mas o noivo onde o encontraremos?<br>Diz o gato que estava no lar:<br>\u2013 Eu estou pronto para me casar.<br>\u2013 Um bom noivo j\u00e1 n\u00f3s temos c\u00e1,<br>A madrinha donde nos vir\u00e1?<br>Diz a cabra da sua casinha:<br>\u2013 Estou pronta para ser a madrinha.<br>\u2013 A madrinha j\u00e1 n\u00f3s temos c\u00e1.<br>O enxoval donde nos vir\u00e1?<br>Diz a aranha do seu aranhal:<br>\u2013 Eu estou pronta para dar o enxoval.<br>\u2013 Enxoval j\u00e1 n\u00f3s temos c\u00e1,<br>A bailarina donde nos vir\u00e1?<br>Diz a mosca que andava no ar:<br>\u2013 Eu estou pronta para vir dan\u00e7ar.<br>\u2013 A bailarina j\u00e1 n\u00f3s temos c\u00e1,<br>O gaiteiro donde nos vir\u00e1?<br>Diz o burro l\u00e1 do seu palheiro:<br>\u2013 Eu estou pronto para ser o gaiteiro.<br>\u2013 O gaiteiro j\u00e1 n\u00f3s temos c\u00e1,<br>O padrinho donde nos vir\u00e1?<br>Diz o rato do seu buraquinho:<br>\u2013 Eu estou pronto para ser o padrinho.<br>Mas o gato ao ver o ratinho,<br>Deu um pulo e comeu o padrinho.<br>Diz a noiva l\u00e1 da capoeira:<br>\u2013 J\u00e1 n\u00e3o caso, ficarei solteira.<br>Os convidados que iam dan\u00e7ar:<br>\u2013 J\u00e1 n\u00e3o temos o nosso jantar.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"675\" height=\"800\" src=\"https:\/\/seedsoftellers.eu\/wp-content\/uploads\/2020\/10\/33.-As-Bodas-da-Capoeira-Marta-G..jpg\" alt=\"\" class=\"wp-image-5517\" srcset=\"https:\/\/seedsoftellers.eu\/wp-content\/uploads\/2020\/10\/33.-As-Bodas-da-Capoeira-Marta-G..jpg 675w, https:\/\/seedsoftellers.eu\/wp-content\/uploads\/2020\/10\/33.-As-Bodas-da-Capoeira-Marta-G.-480x569.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 675px, 100vw\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false},"resource_format":[83],"resource_type":[102],"resource_origin":[122],"resource_genre":[239],"resource_theme":[176],"resource_difficulty":[161],"subtitles":[],"video_language":[],"thematic_cat":[],"class_list":["post-3945","resources","type-resources","status-publish","hentry","resource_format-text-pt","resource_type-tale-pt","resource_origin-mediterranean-pt","resource_genre-tales-pt","resource_theme-customs-traditions-pt","resource_difficulty-level1-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As bodas da capoeira - Seeds Of Tellers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As bodas da capoeira - Seeds Of Tellers\" \/>\n<meta property=\"og:description\" content=\"Diz um dia o galo \u00e0 galinha:\u2013 Casaremos a nossa filhinha!\u2013 Casaremos ou n\u00e3o casaremos,Mas o noivo onde o encontraremos?Diz o gato que estava no lar:\u2013 Eu estou pronto para me casar.\u2013 Um bom noivo j\u00e1 n\u00f3s temos c\u00e1,A madrinha donde nos vir\u00e1?Diz a cabra da sua casinha:\u2013 Estou pronta para ser a madrinha.\u2013 A [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/\" \/>\n<meta property=\"og:site_name\" content=\"Seeds Of Tellers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seedsoftellers.eu\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-21T14:34:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seedsoftellers.eu\/wp-content\/uploads\/2020\/10\/33.-As-Bodas-da-Capoeira-Marta-G..jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/resources\\\/as-bodas-da-capoeira\\\/\",\"url\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/resources\\\/as-bodas-da-capoeira\\\/\",\"name\":\"As bodas da capoeira - Seeds Of Tellers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/resources\\\/as-bodas-da-capoeira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/resources\\\/as-bodas-da-capoeira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seedsoftellers.eu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/33.-As-Bodas-da-Capoeira-Marta-G..jpg\",\"datePublished\":\"2020-09-03T14:35:05+00:00\",\"dateModified\":\"2020-10-21T14:34:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/resources\\\/as-bodas-da-capoeira\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/resources\\\/as-bodas-da-capoeira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/resources\\\/as-bodas-da-capoeira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seedsoftellers.eu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/33.-As-Bodas-da-Capoeira-Marta-G..jpg\",\"contentUrl\":\"https:\\\/\\\/seedsoftellers.eu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/33.-As-Bodas-da-Capoeira-Marta-G..jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/resources\\\/as-bodas-da-capoeira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources\",\"item\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/resources\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"As bodas da capoeira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/\",\"name\":\"Seeds Of Tellers\",\"description\":\"Storytelling for a better oracy\",\"publisher\":{\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/#organization\",\"name\":\"Seeds of Tellers\",\"url\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seedsoftellers.eu\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo_seedsoftellers-1.png\",\"contentUrl\":\"https:\\\/\\\/seedsoftellers.eu\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo_seedsoftellers-1.png\",\"width\":1400,\"height\":584,\"caption\":\"Seeds of Tellers\"},\"image\":{\"@id\":\"https:\\\/\\\/seedsoftellers.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seedsoftellers.eu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As bodas da capoeira - Seeds Of Tellers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/","og_locale":"pt_PT","og_type":"article","og_title":"As bodas da capoeira - Seeds Of Tellers","og_description":"Diz um dia o galo \u00e0 galinha:\u2013 Casaremos a nossa filhinha!\u2013 Casaremos ou n\u00e3o casaremos,Mas o noivo onde o encontraremos?Diz o gato que estava no lar:\u2013 Eu estou pronto para me casar.\u2013 Um bom noivo j\u00e1 n\u00f3s temos c\u00e1,A madrinha donde nos vir\u00e1?Diz a cabra da sua casinha:\u2013 Estou pronta para ser a madrinha.\u2013 A [&hellip;]","og_url":"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/","og_site_name":"Seeds Of Tellers","article_publisher":"https:\/\/www.facebook.com\/seedsoftellers.eu\/","article_modified_time":"2020-10-21T14:34:12+00:00","og_image":[{"url":"https:\/\/seedsoftellers.eu\/wp-content\/uploads\/2020\/10\/33.-As-Bodas-da-Capoeira-Marta-G..jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/","url":"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/","name":"As bodas da capoeira - Seeds Of Tellers","isPartOf":{"@id":"https:\/\/seedsoftellers.eu\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/#primaryimage"},"image":{"@id":"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/#primaryimage"},"thumbnailUrl":"https:\/\/seedsoftellers.eu\/wp-content\/uploads\/2020\/10\/33.-As-Bodas-da-Capoeira-Marta-G..jpg","datePublished":"2020-09-03T14:35:05+00:00","dateModified":"2020-10-21T14:34:12+00:00","breadcrumb":{"@id":"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/#primaryimage","url":"https:\/\/seedsoftellers.eu\/wp-content\/uploads\/2020\/10\/33.-As-Bodas-da-Capoeira-Marta-G..jpg","contentUrl":"https:\/\/seedsoftellers.eu\/wp-content\/uploads\/2020\/10\/33.-As-Bodas-da-Capoeira-Marta-G..jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/as-bodas-da-capoeira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seedsoftellers.eu\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Resources","item":"https:\/\/seedsoftellers.eu\/pt-pt\/resources\/"},{"@type":"ListItem","position":3,"name":"As bodas da capoeira"}]},{"@type":"WebSite","@id":"https:\/\/seedsoftellers.eu\/pt-pt\/#website","url":"https:\/\/seedsoftellers.eu\/pt-pt\/","name":"Seeds Of Tellers","description":"Storytelling for a better oracy","publisher":{"@id":"https:\/\/seedsoftellers.eu\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seedsoftellers.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/seedsoftellers.eu\/pt-pt\/#organization","name":"Seeds of Tellers","url":"https:\/\/seedsoftellers.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/seedsoftellers.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/seedsoftellers.eu\/wp-content\/uploads\/2020\/03\/logo_seedsoftellers-1.png","contentUrl":"https:\/\/seedsoftellers.eu\/wp-content\/uploads\/2020\/03\/logo_seedsoftellers-1.png","width":1400,"height":584,"caption":"Seeds of Tellers"},"image":{"@id":"https:\/\/seedsoftellers.eu\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seedsoftellers.eu\/"]}]}},"_links":{"self":[{"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/resources\/3945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/types\/resources"}],"wp:attachment":[{"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=3945"}],"wp:term":[{"taxonomy":"resource_format","embeddable":true,"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/resource_format?post=3945"},{"taxonomy":"resource_type","embeddable":true,"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/resource_type?post=3945"},{"taxonomy":"resource_origin","embeddable":true,"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/resource_origin?post=3945"},{"taxonomy":"resource_genre","embeddable":true,"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/resource_genre?post=3945"},{"taxonomy":"resource_theme","embeddable":true,"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/resource_theme?post=3945"},{"taxonomy":"resource_difficulty","embeddable":true,"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/resource_difficulty?post=3945"},{"taxonomy":"subtitles","embeddable":true,"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/subtitles?post=3945"},{"taxonomy":"video_language","embeddable":true,"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/video_language?post=3945"},{"taxonomy":"thematic_cat","embeddable":true,"href":"https:\/\/seedsoftellers.eu\/pt-pt\/wp-json\/wp\/v2\/thematic_cat?post=3945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}